{"id":18,"count":7,"description":"","link":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/","name":"Heroes In The Kitchen","slug":"heroes-in-the-kitchen","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heroes In The Kitchen Archives - Home Clean Heroes of the Peninsula<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heroes In The Kitchen Archives - Home Clean Heroes of the Peninsula\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Home Clean Heroes of the Peninsula\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/category\\\/heroes-in-the-kitchen\\\/\",\"url\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/category\\\/heroes-in-the-kitchen\\\/\",\"name\":\"Heroes In The Kitchen Archives - Home Clean Heroes of the Peninsula\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/category\\\/heroes-in-the-kitchen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/category\\\/heroes-in-the-kitchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heroes In The Kitchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/#website\",\"url\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/\",\"name\":\"Home Clean Heroes of the Peninsula\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homecleanheroes.com\\\/peninsula\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heroes In The Kitchen Archives - Home Clean Heroes of the Peninsula","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/","og_locale":"en_US","og_type":"article","og_title":"Heroes In The Kitchen Archives - Home Clean Heroes of the Peninsula","og_url":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/","og_site_name":"Home Clean Heroes of the Peninsula","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/","url":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/","name":"Heroes In The Kitchen Archives - Home Clean Heroes of the Peninsula","isPartOf":{"@id":"https:\/\/homecleanheroes.com\/peninsula\/#website"},"breadcrumb":{"@id":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/homecleanheroes.com\/peninsula\/category\/heroes-in-the-kitchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homecleanheroes.com\/peninsula\/"},{"@type":"ListItem","position":2,"name":"Heroes In The Kitchen"}]},{"@type":"WebSite","@id":"https:\/\/homecleanheroes.com\/peninsula\/#website","url":"https:\/\/homecleanheroes.com\/peninsula\/","name":"Home Clean Heroes of the Peninsula","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homecleanheroes.com\/peninsula\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/homecleanheroes.com\/peninsula\/wp-json\/wp\/v2\/categories\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homecleanheroes.com\/peninsula\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/homecleanheroes.com\/peninsula\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/homecleanheroes.com\/peninsula\/wp-json\/wp\/v2\/posts?categories=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}